{"id":38974,"date":"2025-04-25T16:23:46","date_gmt":"2025-04-25T14:23:46","guid":{"rendered":"https:\/\/gertuago.eus\/?post_type=product&#038;p=38974"},"modified":"2025-04-25T16:27:01","modified_gmt":"2025-04-25T14:27:01","slug":"azken-nobedadeak","status":"publish","type":"product","link":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/","title":{"rendered":"Azken Nobedadeak"},"content":{"rendered":"<p>Lizardi Liburu-dendan ateratzen diren liburu eta produktuekin eguneratuta egotea gustatzen zaigu, horregatik, hemen dituzue Udaberrian ekarri ditugun azken nobedadeak.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lizardi Liburu-dendan ateratzen diren liburu eta produktuekin eguneratuta egotea gustatzen zaigu, horregatik, hemen dituzue Udaberrian ekarri ditugun azken nobedadeak.<\/p>\n","protected":false},"featured_media":38975,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[89],"product_tag":[],"class_list":["post-38974","product","type-product","status-publish","has-post-thumbnail","product_cat-liburuak-eskolako-materiala-eta-jostailuak","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Azken Nobedadeak - Gertuago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Azken Nobedadeak - Gertuago\" \/>\n<meta property=\"og:description\" content=\"Lizardi Liburu-dendan ateratzen diren liburu eta produktuekin eguneratuta egotea gustatzen zaigu, horregatik, hemen dituzue Udaberrian ekarri ditugun azken nobedadeak.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/\" \/>\n<meta property=\"og:site_name\" content=\"Gertuago\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T14:27:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/04\/nobedadeak-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1530\" \/>\n\t<meta property=\"og:image:height\" content=\"2040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/\",\"name\":\"Azken Nobedadeak - Gertuago\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/nobedadeak-1.jpeg\",\"datePublished\":\"2025-04-25T14:23:46+00:00\",\"dateModified\":\"2025-04-25T14:27:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/nobedadeak-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/nobedadeak-1.jpeg\",\"width\":1530,\"height\":2040},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/produktua\\\/azken-nobedadeak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dendak &#8211; woocommerce\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/dendak-woocommerce\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Azken Nobedadeak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\",\"name\":\"Gertuago\",\"description\":\"Usurbil Merkataritza Bonoak\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Azken Nobedadeak - Gertuago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/","og_locale":"en_US","og_type":"article","og_title":"Azken Nobedadeak - Gertuago","og_description":"Lizardi Liburu-dendan ateratzen diren liburu eta produktuekin eguneratuta egotea gustatzen zaigu, horregatik, hemen dituzue Udaberrian ekarri ditugun azken nobedadeak.","og_url":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/","og_site_name":"Gertuago","article_modified_time":"2025-04-25T14:27:01+00:00","og_image":[{"width":1530,"height":2040,"url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/04\/nobedadeak-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/","url":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/","name":"Azken Nobedadeak - Gertuago","isPartOf":{"@id":"https:\/\/gertuago.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/#primaryimage"},"image":{"@id":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/04\/nobedadeak-1.jpeg","datePublished":"2025-04-25T14:23:46+00:00","dateModified":"2025-04-25T14:27:01+00:00","breadcrumb":{"@id":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/#primaryimage","url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/04\/nobedadeak-1.jpeg","contentUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/04\/nobedadeak-1.jpeg","width":1530,"height":2040},{"@type":"BreadcrumbList","@id":"https:\/\/gertuago.eus\/eu\/produktua\/azken-nobedadeak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gertuago.eus\/eu\/"},{"@type":"ListItem","position":2,"name":"Dendak &#8211; woocommerce","item":"https:\/\/gertuago.eus\/eu\/dendak-woocommerce\/"},{"@type":"ListItem","position":3,"name":"Azken Nobedadeak"}]},{"@type":"WebSite","@id":"https:\/\/gertuago.eus\/es\/#website","url":"https:\/\/gertuago.eus\/es\/","name":"Gertuago","description":"Usurbil Merkataritza Bonoak","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gertuago.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"}]}},"_links":{"self":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/product\/38974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/media\/38975"}],"wp:attachment":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/media?parent=38974"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/product_brand?post=38974"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/product_cat?post=38974"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/product_tag?post=38974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}