{"id":33011,"date":"2023-06-12T07:17:36","date_gmt":"2023-06-12T07:17:36","guid":{"rendered":"https:\/\/gertuago.eus\/?p=33011"},"modified":"2023-06-12T15:09:16","modified_gmt":"2023-06-12T15:09:16","slug":"ekainaren-19tik-aurrera-eko-deskontu-zuzena","status":"publish","type":"post","link":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/","title":{"rendered":"Ekainaren 19tik aurrera %10eko deskontu zuzena, GERTU txartela erabilita, HURBILAGO-ko saltokietan"},"content":{"rendered":"<p>HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, %10eko deskontu zuzena egingo da erosketa guztietan. Erosketa bakoitzeko, gehienez 10 euroko deskontua lortu ahal izango da. Ekainaren 19tik aurrera hasiko da kanpaina eta deskontuetarako HURBILAGO elkarteak ezarritako aurrekontua agortu arte egongo da martxan.<\/p>\n<p>Erosketa bakoitzean aplikatuko da deskontua, beraz, establezimentu ezberdinetan erabiltzeko aukera dago. Hauek dira GERTU txartelarekin deskontuak lortu daitezkeen HURBILAGO elkarteko bazkideak:<\/p>\n<ul>\n<li>Janari dendak: Esnaola janari denda, Iratze natur denda eta Otar-goxo<\/li>\n<li>Kafetegi eta okindegiak: Aizpurua okindegia eta Laukote okindegi-kafetegia<\/li>\n<li>Liburu dendak: Laurok liburudenda eta Lizardi liburudenda<\/li>\n<li>Baserritarren kooperatiba: Alkartasuna Nekazal Kooperatiba<\/li>\n<li>Eraikuntzak: Itzira Eraikuntzak<\/li>\n<li>Zaintza eta Osasuna: Ane ileapaindegia (Artzabal), NI ileapaindegia, Intza Ileapaindegia eta Usurbil Optika<\/li>\n<li>Taberna eta jatetxeak: Artzabal Baserria-Jatetxea, Bordatxo taberna, Guria taberna eta Txirristra Taberna<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, %10eko deskontu zuzena egingo da erosketa guztietan. Erosketa bakoitzeko, gehienez 10 euroko deskontua lortu ahal izango da. Ekainaren 19tik aurrera hasiko da kanpaina eta deskontuetarako HURBILAGO elkarteak ezarritako aurrekontua agortu arte egongo da martxan. Erosketa bakoitzean aplikatuko da deskontua, beraz, establezimentu ezberdinetan erabiltzeko aukera dago. Hauek dira GERTU txartelarekin&#8230;<\/p>\n","protected":false},"author":556,"featured_media":33012,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1],"tags":[],"class_list":["post-33011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-eu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ekainaren 19tik aurrera eko deskontu zuzena<\/title>\n<meta name=\"description\" content=\"HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, eko deskontu zuzena egingo da erosketa guztietan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ekainaren 19tik aurrera eko deskontu zuzena\" \/>\n<meta property=\"og:description\" content=\"HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, eko deskontu zuzena egingo da erosketa guztietan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/\" \/>\n<meta property=\"og:site_name\" content=\"Gertuago\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T07:17:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T15:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bereziartua(e)ko Uxue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bereziartua(e)ko Uxue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minutua\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/\"},\"author\":{\"name\":\"Bereziartua(e)ko Uxue\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#\\\/schema\\\/person\\\/2f69708f848c7b42c760eb7f3950fb3c\"},\"headline\":\"Ekainaren 19tik aurrera %10eko deskontu zuzena, GERTU txartela erabilita, HURBILAGO-ko saltokietan\",\"datePublished\":\"2023-06-12T07:17:36+00:00\",\"dateModified\":\"2023-06-12T15:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/\"},\"wordCount\":129,\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"articleSection\":[\"Uncategorized @eu\"],\"inLanguage\":\"eu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/\",\"name\":\"Ekainaren 19tik aurrera eko deskontu zuzena\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"datePublished\":\"2023-06-12T07:17:36+00:00\",\"dateModified\":\"2023-06-12T15:09:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#\\\/schema\\\/person\\\/2f69708f848c7b42c760eb7f3950fb3c\"},\"description\":\"HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, eko deskontu zuzena egingo da erosketa guztietan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/#breadcrumb\"},\"inLanguage\":\"eu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"width\":2560,\"height\":1810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekainaren 19tik aurrera %10eko deskontu zuzena, GERTU txartela erabilita, HURBILAGO-ko saltokietan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\",\"name\":\"Gertuago\",\"description\":\"Usurbil Merkataritza Bonoak\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#\\\/schema\\\/person\\\/2f69708f848c7b42c760eb7f3950fb3c\",\"name\":\"Bereziartua(e)ko Uxue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g\",\"caption\":\"Bereziartua(e)ko Uxue\"},\"url\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/author\\\/uxue\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ekainaren 19tik aurrera eko deskontu zuzena","description":"HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, eko deskontu zuzena egingo da erosketa guztietan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/","og_locale":"en_US","og_type":"article","og_title":"Ekainaren 19tik aurrera eko deskontu zuzena","og_description":"HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, eko deskontu zuzena egingo da erosketa guztietan.","og_url":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/","og_site_name":"Gertuago","article_published_time":"2023-06-12T07:17:36+00:00","article_modified_time":"2023-06-12T15:09:16+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","type":"image\/jpeg"}],"author":"Bereziartua(e)ko Uxue","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Bereziartua(e)ko Uxue","Est. reading time":"1 minutua"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/#article","isPartOf":{"@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/"},"author":{"name":"Bereziartua(e)ko Uxue","@id":"https:\/\/gertuago.eus\/es\/#\/schema\/person\/2f69708f848c7b42c760eb7f3950fb3c"},"headline":"Ekainaren 19tik aurrera %10eko deskontu zuzena, GERTU txartela erabilita, HURBILAGO-ko saltokietan","datePublished":"2023-06-12T07:17:36+00:00","dateModified":"2023-06-12T15:09:16+00:00","mainEntityOfPage":{"@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/"},"wordCount":129,"image":{"@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","articleSection":["Uncategorized @eu"],"inLanguage":"eu"},{"@type":"WebPage","@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/","url":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/","name":"Ekainaren 19tik aurrera eko deskontu zuzena","isPartOf":{"@id":"https:\/\/gertuago.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/#primaryimage"},"image":{"@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","datePublished":"2023-06-12T07:17:36+00:00","dateModified":"2023-06-12T15:09:16+00:00","author":{"@id":"https:\/\/gertuago.eus\/es\/#\/schema\/person\/2f69708f848c7b42c760eb7f3950fb3c"},"description":"HURBILAGO-koak diren saltokietan GERTU txartelarekin ordainduta, eko deskontu zuzena egingo da erosketa guztietan.","breadcrumb":{"@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/#breadcrumb"},"inLanguage":"eu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/"]}]},{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/#primaryimage","url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","contentUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","width":2560,"height":1810},{"@type":"BreadcrumbList","@id":"https:\/\/gertuago.eus\/eu\/ekainaren-19tik-aurrera-eko-deskontu-zuzena\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gertuago.eus\/eu\/"},{"@type":"ListItem","position":2,"name":"Ekainaren 19tik aurrera %10eko deskontu zuzena, GERTU txartela erabilita, HURBILAGO-ko saltokietan"}]},{"@type":"WebSite","@id":"https:\/\/gertuago.eus\/es\/#website","url":"https:\/\/gertuago.eus\/es\/","name":"Gertuago","description":"Usurbil Merkataritza Bonoak","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gertuago.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu"},{"@type":"Person","@id":"https:\/\/gertuago.eus\/es\/#\/schema\/person\/2f69708f848c7b42c760eb7f3950fb3c","name":"Bereziartua(e)ko Uxue","image":{"@type":"ImageObject","inLanguage":"eu","@id":"https:\/\/secure.gravatar.com\/avatar\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g","caption":"Bereziartua(e)ko Uxue"},"url":"https:\/\/gertuago.eus\/eu\/author\/uxue\/"}]}},"_links":{"self":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/posts\/33011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/users\/556"}],"replies":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/comments?post=33011"}],"version-history":[{"count":2,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/posts\/33011\/revisions"}],"predecessor-version":[{"id":33017,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/posts\/33011\/revisions\/33017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/media\/33012"}],"wp:attachment":[{"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/media?parent=33011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/categories?post=33011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gertuago.eus\/eu\/wp-json\/wp\/v2\/tags?post=33011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}