{"id":43706,"date":"2026-02-24T19:56:47","date_gmt":"2026-02-24T18:56:47","guid":{"rendered":"https:\/\/gertuago.eus\/?post_type=product&#038;p=43706"},"modified":"2026-04-09T13:46:26","modified_gmt":"2026-04-09T11:46:26","slug":"carta-2","status":"publish","type":"product","link":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/","title":{"rendered":"Carta"},"content":{"rendered":"<p>Tanto durante la semana como los fines de semana ofrecemos una carta para que pod\u00e1is disfrutar de una amplia oferta de alimentos de calidad en vuestras comidas y\/o cenas.<\/p>\n<p>Adecuamos la carta a los productos de temporada para ofreceros los mejores productos de cada temporada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tanto durante la semana como los fines de semana ofrecemos una carta para que pod\u00e1is disfrutar de una amplia oferta de alimentos de calidad en vuestras comidas y\/o cenas. Adecuamos la carta a los productos de temporada para ofreceros los mejores productos de cada temporada.<\/p>\n","protected":false},"featured_media":43701,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[110],"product_tag":[],"class_list":["post-43706","product","type-product","status-publish","has-post-thumbnail","product_cat-bares-restaurantes-y-sidrerias","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta - Gertuago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gertuago.eus\/es\/producto\/carta-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta - Gertuago\" \/>\n<meta property=\"og:description\" content=\"Tanto durante la semana como los fines de semana ofrecemos una carta para que pod\u00e1is disfrutar de una amplia oferta de alimentos de calidad en vuestras comidas y\/o cenas. Adecuamos la carta a los productos de temporada para ofreceros los mejores productos de cada temporada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gertuago.eus\/es\/producto\/carta-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Gertuago\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-09T11:46:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gertuago.eus\/wp-content\/uploads\/2026\/02\/menuak.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/\",\"name\":\"Carta - Gertuago\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/menuak.jpg\",\"datePublished\":\"2026-02-24T18:56:47+00:00\",\"dateModified\":\"2026-04-09T11:46:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/menuak.jpg\",\"contentUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/menuak.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/carta-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dendak &#8211; woocommerce\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/dendak-woocommerce\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\",\"name\":\"Gertuago\",\"description\":\"Usurbil Merkataritza Bonoak\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta - Gertuago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/","og_locale":"es_ES","og_type":"article","og_title":"Carta - Gertuago","og_description":"Tanto durante la semana como los fines de semana ofrecemos una carta para que pod\u00e1is disfrutar de una amplia oferta de alimentos de calidad en vuestras comidas y\/o cenas. Adecuamos la carta a los productos de temporada para ofreceros los mejores productos de cada temporada.","og_url":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/","og_site_name":"Gertuago","article_modified_time":"2026-04-09T11:46:26+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2026\/02\/menuak.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/","url":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/","name":"Carta - Gertuago","isPartOf":{"@id":"https:\/\/gertuago.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/#primaryimage"},"image":{"@id":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2026\/02\/menuak.jpg","datePublished":"2026-02-24T18:56:47+00:00","dateModified":"2026-04-09T11:46:26+00:00","breadcrumb":{"@id":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gertuago.eus\/es\/producto\/carta-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/#primaryimage","url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2026\/02\/menuak.jpg","contentUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2026\/02\/menuak.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/gertuago.eus\/es\/producto\/carta-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gertuago.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Dendak &#8211; woocommerce","item":"https:\/\/gertuago.eus\/eu\/dendak-woocommerce\/"},{"@type":"ListItem","position":3,"name":"Carta"}]},{"@type":"WebSite","@id":"https:\/\/gertuago.eus\/es\/#website","url":"https:\/\/gertuago.eus\/es\/","name":"Gertuago","description":"Usurbil Merkataritza Bonoak","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gertuago.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product\/43706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/media?parent=43706"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_brand?post=43706"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_cat?post=43706"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_tag?post=43706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}