{"id":38631,"date":"2025-03-07T19:50:39","date_gmt":"2025-03-07T18:50:39","guid":{"rendered":"https:\/\/gertuago.eus\/?post_type=product&#038;p=38631"},"modified":"2025-03-07T19:50:39","modified_gmt":"2025-03-07T18:50:39","slug":"asesoramiento","status":"publish","type":"product","link":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/","title":{"rendered":"Asesoramiento"},"content":{"rendered":"<p>En Zumitza Eraiketak nos parece muy importante ofrecer un asesoramiento adecuado a los clientes, por lo que en el proceso de construcci\u00f3n te informaremos sobre la calidad de los materiales, la sostenibilidad, etc.<\/p>\n<p>Ayud\u00e1ndote a llevar a cabo el proyecto que mejor se adapte a tus necesidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Zumitza Eraiketak nos parece muy importante ofrecer un asesoramiento adecuado a los clientes, por lo que en el proceso de construcci\u00f3n te informaremos sobre la calidad de los materiales, la sostenibilidad, etc. Ayud\u00e1ndote a llevar a cabo el proyecto que mejor se adapte a tus necesidades.<\/p>\n","protected":false},"featured_media":38621,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[118],"product_tag":[],"class_list":["post-38631","product","type-product","status-publish","has-post-thumbnail","product_cat-construccion","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asesoramiento - Gertuago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asesoramiento - Gertuago\" \/>\n<meta property=\"og:description\" content=\"En Zumitza Eraiketak nos parece muy importante ofrecer un asesoramiento adecuado a los clientes, por lo que en el proceso de construcci\u00f3n te informaremos sobre la calidad de los materiales, la sostenibilidad, etc. Ayud\u00e1ndote a llevar a cabo el proyecto que mejor se adapte a tus necesidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Gertuago\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/02\/aholkularitza-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/\",\"name\":\"Asesoramiento - Gertuago\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/aholkularitza.jpg\",\"datePublished\":\"2025-03-07T18:50:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/aholkularitza.jpg\",\"contentUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/aholkularitza.jpg\",\"width\":7952,\"height\":5304},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/asesoramiento\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dendak &#8211; woocommerce\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/dendak-woocommerce\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Asesoramiento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\",\"name\":\"Gertuago\",\"description\":\"Usurbil Merkataritza Bonoak\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asesoramiento - Gertuago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/","og_locale":"es_ES","og_type":"article","og_title":"Asesoramiento - Gertuago","og_description":"En Zumitza Eraiketak nos parece muy importante ofrecer un asesoramiento adecuado a los clientes, por lo que en el proceso de construcci\u00f3n te informaremos sobre la calidad de los materiales, la sostenibilidad, etc. Ayud\u00e1ndote a llevar a cabo el proyecto que mejor se adapte a tus necesidades.","og_url":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/","og_site_name":"Gertuago","og_image":[{"width":1024,"height":683,"url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/02\/aholkularitza-1024x683.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/","url":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/","name":"Asesoramiento - Gertuago","isPartOf":{"@id":"https:\/\/gertuago.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/#primaryimage"},"image":{"@id":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/02\/aholkularitza.jpg","datePublished":"2025-03-07T18:50:39+00:00","breadcrumb":{"@id":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/#primaryimage","url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/02\/aholkularitza.jpg","contentUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/02\/aholkularitza.jpg","width":7952,"height":5304},{"@type":"BreadcrumbList","@id":"https:\/\/gertuago.eus\/es\/producto\/asesoramiento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gertuago.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Dendak &#8211; woocommerce","item":"https:\/\/gertuago.eus\/eu\/dendak-woocommerce\/"},{"@type":"ListItem","position":3,"name":"Asesoramiento"}]},{"@type":"WebSite","@id":"https:\/\/gertuago.eus\/es\/#website","url":"https:\/\/gertuago.eus\/es\/","name":"Gertuago","description":"Usurbil Merkataritza Bonoak","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gertuago.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product\/38631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/media\/38621"}],"wp:attachment":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/media?parent=38631"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_brand?post=38631"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_cat?post=38631"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_tag?post=38631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}