{"id":38349,"date":"2025-01-29T11:59:51","date_gmt":"2025-01-29T11:06:23","guid":{"rendered":"https:\/\/gertuago.eus\/?post_type=product&#038;p=38349"},"modified":"2025-01-29T12:06:23","modified_gmt":"2025-01-29T11:06:23","slug":"depilacion-laser-2","status":"publish","type":"product","link":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/","title":{"rendered":"Depilaci\u00f3n L\u00e1ser"},"content":{"rendered":"<div>\n<p><strong>Depitotal (IPL)<\/strong><\/p>\n<p>Mediante la aparatolog\u00eda de IPL (luz pulsada intensa), conseguimos reducir eficazmente el vello no deseado, ofreciendo resultados duraderos y una piel m\u00e1s suave. Aparte de eso, tambi\u00e9n ayuda a tratar diversas imperfecciones cut\u00e1neas, ofreciendo as\u00ed muchos beneficios.<\/p>\n<ul>\n<li>Manchas solares.<\/li>\n<li>Hiperpigmentaci\u00f3n.<\/li>\n<li>Ros\u00e1cea.<\/li>\n<li>Mejora el tono y la textura de la piel.<\/li>\n<li>Estimula la producci\u00f3n de col\u00e1geno.<\/li>\n<li>Piel m\u00e1s firme y rejuvenecida.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<\/div>\n<div>\n<p><strong>LightSheer (diodo)<\/strong><\/p>\n<div class=\"zb-ap_bat-testua\">\n<p>Con la aparatolog\u00eda de LightSheer, ofrecemos servicios de depilaci\u00f3n incluso a pieles m\u00e1s bronceadas y el vello m\u00e1s claro; ya que gracias a su tecnolog\u00eda y su alta potencia y control de par\u00e1metros permiten el tratamiento en vello de pr\u00e1cticamente cualquier di\u00e1metro o color.<\/p>\n<ul>\n<li>R\u00e1pido y c\u00f3modo.<\/li>\n<li>Depilaci\u00f3n duradera y definitiva.<\/li>\n<li>Eficaz para tratar foliculitis o hirsutismo.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Depitotal (IPL) Mediante la aparatolog\u00eda de IPL (luz pulsada intensa), conseguimos reducir eficazmente el vello no deseado, ofreciendo resultados duraderos y una piel m\u00e1s suave. Aparte de eso, tambi\u00e9n ayuda a tratar diversas imperfecciones cut\u00e1neas, ofreciendo as\u00ed muchos beneficios. Manchas solares. Hiperpigmentaci\u00f3n. Ros\u00e1cea. Mejora el tono y la textura de la piel. Estimula la producci\u00f3n&#8230;<\/p>\n","protected":false},"featured_media":38346,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[],"product_tag":[],"class_list":["post-38349","product","type-product","status-publish","has-post-thumbnail","first","instock","taxable","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Depilaci\u00f3n L\u00e1ser - Gertuago<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Depilaci\u00f3n L\u00e1ser - Gertuago\" \/>\n<meta property=\"og:description\" content=\"Depitotal (IPL) Mediante la aparatolog\u00eda de IPL (luz pulsada intensa), conseguimos reducir eficazmente el vello no deseado, ofreciendo resultados duraderos y una piel m\u00e1s suave. Aparte de eso, tambi\u00e9n ayuda a tratar diversas imperfecciones cut\u00e1neas, ofreciendo as\u00ed muchos beneficios. Manchas solares. Hiperpigmentaci\u00f3n. Ros\u00e1cea. Mejora el tono y la textura de la piel. Estimula la producci\u00f3n...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Gertuago\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/01\/depilacion-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/\",\"name\":\"Depilaci\u00f3n L\u00e1ser - Gertuago\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/depilacion-01.jpg\",\"datePublished\":\"2025-01-29T11:06:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/depilacion-01.jpg\",\"contentUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/depilacion-01.jpg\",\"width\":660,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/producto\\\/depilacion-laser-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dendak &#8211; woocommerce\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/eu\\\/dendak-woocommerce\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Depilaci\u00f3n L\u00e1ser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\",\"name\":\"Gertuago\",\"description\":\"Usurbil Merkataritza Bonoak\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Depilaci\u00f3n L\u00e1ser - Gertuago","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/","og_locale":"es_ES","og_type":"article","og_title":"Depilaci\u00f3n L\u00e1ser - Gertuago","og_description":"Depitotal (IPL) Mediante la aparatolog\u00eda de IPL (luz pulsada intensa), conseguimos reducir eficazmente el vello no deseado, ofreciendo resultados duraderos y una piel m\u00e1s suave. Aparte de eso, tambi\u00e9n ayuda a tratar diversas imperfecciones cut\u00e1neas, ofreciendo as\u00ed muchos beneficios. Manchas solares. Hiperpigmentaci\u00f3n. Ros\u00e1cea. Mejora el tono y la textura de la piel. Estimula la producci\u00f3n...","og_url":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/","og_site_name":"Gertuago","og_image":[{"width":660,"height":580,"url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/01\/depilacion-01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/","url":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/","name":"Depilaci\u00f3n L\u00e1ser - Gertuago","isPartOf":{"@id":"https:\/\/gertuago.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/#primaryimage"},"image":{"@id":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/01\/depilacion-01.jpg","datePublished":"2025-01-29T11:06:23+00:00","breadcrumb":{"@id":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/#primaryimage","url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/01\/depilacion-01.jpg","contentUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2025\/01\/depilacion-01.jpg","width":660,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/gertuago.eus\/es\/producto\/depilacion-laser-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gertuago.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Dendak &#8211; woocommerce","item":"https:\/\/gertuago.eus\/eu\/dendak-woocommerce\/"},{"@type":"ListItem","position":3,"name":"Depilaci\u00f3n L\u00e1ser"}]},{"@type":"WebSite","@id":"https:\/\/gertuago.eus\/es\/#website","url":"https:\/\/gertuago.eus\/es\/","name":"Gertuago","description":"Usurbil Merkataritza Bonoak","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gertuago.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product\/38349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/media\/38346"}],"wp:attachment":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/media?parent=38349"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_brand?post=38349"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_cat?post=38349"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/product_tag?post=38349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}