{"id":33015,"date":"2023-06-12T07:21:44","date_gmt":"2023-06-12T07:21:44","guid":{"rendered":"https:\/\/gertuago.eus\/?p=33015"},"modified":"2023-06-12T15:10:17","modified_gmt":"2023-06-12T15:10:17","slug":"descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago","status":"publish","type":"post","link":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/","title":{"rendered":"Descuento directo del 10% a partir del 19 de junio con tarjeta GERTU en los comercios de HURBILAGO"},"content":{"rendered":"<p>El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras. Se podr\u00e1 obtener un descuento m\u00e1ximo de 10 euros por compra. La campa\u00f1a empezar\u00e1 el 19 de junio y estar\u00e1 en marcha hasta agotar el presupuesto establecido por la Asociaci\u00f3n.<\/p>\n<p>El descuento se aplicar\u00e1 en cada compra, por lo que existe la posibilidad de utilizarlo en diferentes establecimientos. Los establecimientos de HURBILAGO que permite obtener descuentos con la tarjeta GERTU son:<\/p>\n<ul>\n<li>Alimentaci\u00f3n: Esnaola janari denda, Iratze natur denda y Otar-goxo<\/li>\n<li>Cafeter\u00edas y panader\u00edas: Aizpurua okindegia y Laukote okindegi-kafetegia<\/li>\n<li>Librer\u00edas: Laurok liburudenda eta Lizardi liburudenda<\/li>\n<li>Cooperativa de baserritarras: Alkartasuna Nekazal Kooperatiba<\/li>\n<li>Construcciones: Itzira Eraikuntzak<\/li>\n<li>Cuidado y salud: Ane ileapaindegia (Artzabal), NI ileapaindegia, Intza Ileapaindegia y Usurbil Optika<\/li>\n<li>Bares y restaurantes: Artzabal Baserria-Jatetxea, Bordatxo taberna, Guria taberna eta Txirristra Taberna<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras. Se podr\u00e1 obtener un descuento m\u00e1ximo de 10 euros por compra. La campa\u00f1a empezar\u00e1 el 19 de junio y estar\u00e1 en marcha hasta agotar el presupuesto establecido por la Asociaci\u00f3n. El descuento se aplicar\u00e1&#8230;<\/p>\n","protected":false},"author":556,"featured_media":33013,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[22],"tags":[],"class_list":["post-33015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Descuento directo del 10% a partir del 19 de junio<\/title>\n<meta name=\"description\" content=\"El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descuento directo del 10% a partir del 19 de junio\" \/>\n<meta property=\"og:description\" content=\"El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/\" \/>\n<meta property=\"og:site_name\" content=\"Gertuago\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T07:21:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T15:10:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bereziartua(e)ko Uxue\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bereziartua(e)ko Uxue\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/\"},\"author\":{\"name\":\"Bereziartua(e)ko Uxue\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#\\\/schema\\\/person\\\/2f69708f848c7b42c760eb7f3950fb3c\"},\"headline\":\"Descuento directo del 10% a partir del 19 de junio con tarjeta GERTU en los comercios de HURBILAGO\",\"datePublished\":\"2023-06-12T07:21:44+00:00\",\"dateModified\":\"2023-06-12T15:10:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/\"},\"wordCount\":159,\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/\",\"name\":\"Descuento directo del 10% a partir del 19 de junio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"datePublished\":\"2023-06-12T07:21:44+00:00\",\"dateModified\":\"2023-06-12T15:10:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#\\\/schema\\\/person\\\/2f69708f848c7b42c760eb7f3950fb3c\"},\"description\":\"El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gertuago.eus\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/HORIZONTALA-scaled.jpg\",\"width\":2560,\"height\":1810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descuento directo del 10% a partir del 19 de junio con tarjeta GERTU en los comercios de HURBILAGO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/\",\"name\":\"Gertuago\",\"description\":\"Usurbil Merkataritza Bonoak\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/#\\\/schema\\\/person\\\/2f69708f848c7b42c760eb7f3950fb3c\",\"name\":\"Bereziartua(e)ko Uxue\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g\",\"caption\":\"Bereziartua(e)ko Uxue\"},\"url\":\"https:\\\/\\\/gertuago.eus\\\/es\\\/author\\\/uxue\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descuento directo del 10% a partir del 19 de junio","description":"El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/","og_locale":"es_ES","og_type":"article","og_title":"Descuento directo del 10% a partir del 19 de junio","og_description":"El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras.","og_url":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/","og_site_name":"Gertuago","article_published_time":"2023-06-12T07:21:44+00:00","article_modified_time":"2023-06-12T15:10:17+00:00","og_image":[{"width":2560,"height":1810,"url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","type":"image\/jpeg"}],"author":"Bereziartua(e)ko Uxue","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bereziartua(e)ko Uxue","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/#article","isPartOf":{"@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/"},"author":{"name":"Bereziartua(e)ko Uxue","@id":"https:\/\/gertuago.eus\/es\/#\/schema\/person\/2f69708f848c7b42c760eb7f3950fb3c"},"headline":"Descuento directo del 10% a partir del 19 de junio con tarjeta GERTU en los comercios de HURBILAGO","datePublished":"2023-06-12T07:21:44+00:00","dateModified":"2023-06-12T15:10:17+00:00","mainEntityOfPage":{"@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/"},"wordCount":159,"image":{"@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/","url":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/","name":"Descuento directo del 10% a partir del 19 de junio","isPartOf":{"@id":"https:\/\/gertuago.eus\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/#primaryimage"},"image":{"@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/#primaryimage"},"thumbnailUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","datePublished":"2023-06-12T07:21:44+00:00","dateModified":"2023-06-12T15:10:17+00:00","author":{"@id":"https:\/\/gertuago.eus\/es\/#\/schema\/person\/2f69708f848c7b42c760eb7f3950fb3c"},"description":"El pago con la tarjeta GERTU en los comercios de HURBILAGO supondr\u00e1 un 10% de descuento directo en todas las compras.","breadcrumb":{"@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/#primaryimage","url":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","contentUrl":"https:\/\/gertuago.eus\/wp-content\/uploads\/2023\/06\/HORIZONTALA-scaled.jpg","width":2560,"height":1810},{"@type":"BreadcrumbList","@id":"https:\/\/gertuago.eus\/es\/descuento-directo-del-10-a-partir-del-19-de-junio-con-tarjeta-gertu-en-los-comercios-de-hurbilago\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gertuago.eus\/es\/"},{"@type":"ListItem","position":2,"name":"Descuento directo del 10% a partir del 19 de junio con tarjeta GERTU en los comercios de HURBILAGO"}]},{"@type":"WebSite","@id":"https:\/\/gertuago.eus\/es\/#website","url":"https:\/\/gertuago.eus\/es\/","name":"Gertuago","description":"Usurbil Merkataritza Bonoak","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gertuago.eus\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gertuago.eus\/es\/#\/schema\/person\/2f69708f848c7b42c760eb7f3950fb3c","name":"Bereziartua(e)ko Uxue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b7b5205eaf2edaaeae37f4ad7ec9fb91300725a5c3a6dfe40cf1dbfda9fe600?s=96&d=mm&r=g","caption":"Bereziartua(e)ko Uxue"},"url":"https:\/\/gertuago.eus\/es\/author\/uxue\/"}]}},"_links":{"self":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/posts\/33015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/users\/556"}],"replies":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/comments?post=33015"}],"version-history":[{"count":2,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/posts\/33015\/revisions"}],"predecessor-version":[{"id":33018,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/posts\/33015\/revisions\/33018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/media\/33013"}],"wp:attachment":[{"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/media?parent=33015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/categories?post=33015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gertuago.eus\/es\/wp-json\/wp\/v2\/tags?post=33015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}